{"id":1913,"date":"2013-02-01T15:20:45","date_gmt":"2013-02-01T15:20:45","guid":{"rendered":"http:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript.jpg"},"modified":"2013-02-01T15:20:45","modified_gmt":"2013-02-01T15:20:45","slug":"hunt-manuscript","status":"inherit","type":"attachment","link":"https:\/\/blog.lib.uiowa.edu\/speccoll\/2013\/02\/01\/leigh-hunts-fireplace\/hunt-manuscript\/","title":{"rendered":"hunt-manuscript"},"author":130,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-1913","attachment","type-attachment","status-inherit","hentry","no-blocks","entry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"300\" src=\"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript-190x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript-190x300.jpg 190w, https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript.jpg 468w\" sizes=\"auto, (max-width: 190px) 100vw, 190px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>The first page of Hunt&#8217;s manuscript for Old Court Suburb, containing notes about the work.<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":468,"height":736,"file":"2013\/02\/hunt-manuscript.jpg","sizes":{"thumbnail":{"file":"hunt-manuscript-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript-150x150.jpg"},"medium":{"file":"hunt-manuscript-190x300.jpg","width":190,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript-190x300.jpg"},"single-thumb":{"file":"hunt-manuscript-468x250.jpg","width":468,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript-468x250.jpg"},"sidebar-thumb":{"file":"hunt-manuscript-36x36.jpg","width":36,"height":36,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript-36x36.jpg"},"featured-slideshow-thumb":{"file":"hunt-manuscript-468x250.jpg","width":468,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript-468x250.jpg"},"node-based-thumb":{"file":"hunt-manuscript-195x110.jpg","width":195,"height":110,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript-195x110.jpg"},"quick-preview-thumb":{"file":"hunt-manuscript-115x115.jpg","width":115,"height":115,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript-115x115.jpg"},"full":{"file":"hunt-manuscript.jpg","width":468,"height":736,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":1905,"source_url":"https:\/\/blog.lib.uiowa.edu\/speccoll\/files\/2013\/02\/hunt-manuscript.jpg","filename":"hunt-manuscript.jpg","filesize":399058,"_links":{"self":[{"href":"https:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/media\/1913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/users\/130"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/comments?post=1913"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1905,"href":"https:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/posts\/1905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}