{"id":206,"count":1,"description":"","link":"http:\/\/blog.lib.uiowa.edu\/speccoll\/tag\/stewart-stern\/","name":"stewart stern","slug":"stewart-stern","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/tags\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/blog.lib.uiowa.edu\/speccoll\/wp-json\/wp\/v2\/posts?tags=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}